{"id":10000089,"date":"2023-10-05T09:34:42","date_gmt":"2023-10-05T13:34:42","guid":{"rendered":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/?post_type=tribe_events&#038;p=21104"},"modified":"2025-05-08T14:26:08","modified_gmt":"2025-05-08T18:26:08","slug":"le-reseau-de-coaching-en-litteratie-serie","status":"publish","type":"tribe_events","link":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/event\/le-reseau-de-coaching-en-litteratie-serie\/2023-10-30\/","title":{"rendered":"Le r\u00e9seau de coaching en litt\u00e9ratie"},"content":{"rendered":"<p>Joignez-vous \u00e0 Jordan Sloan pour cette S\u00e9rie de ONLit, <strong>Le r\u00e9seau de coaching en litt\u00e9ratie<\/strong>. Notre travail commencera avec une \u00e9tude du livre de Jennifer Pierce et Kimberly St. Martin, <em>Coaching for Systems and Teacher Change<\/em>. Le coaching entre \u00e9ducateurs est l\u2019un des meilleurs moyens d\u2019am\u00e9liorer les r\u00e9sultats de tous les \u00e9l\u00e8ves, mais les coachs b\u00e9n\u00e9ficient rarement d\u2019une pr\u00e9paration formelle pour ma\u00eetriser ce r\u00f4le important. Ce guide complet combine des recherches pertinentes avec des conseils pratiques et des ressources pour travailler avec le personnel enseignant de la maternelle \u00e0 la 12e ann\u00e9e.<\/p>\n<p>Nous explorerons le coaching dans le contexte du nouveau programme-cadre de Fran\u00e7ais avec un aper\u00e7u d\u2019un chapitre ou article, une pr\u00e9sentation du mat\u00e9riel d\u2019appui et une discussion avec les participantes et les participants en groupe entier et en s\u00e9ances break-out. Les sessions dureront 40 minutes, avec la possibilit\u00e9 de rester en ligne pendant 10 \u00e0 15 minutes pour aborder des questions ou des points de discussion suppl\u00e9mentaires.<\/p>\n<p>Inscrivez-vous maintenant pour participer \u00e0 la discussion avec des coachs, des consultantes et des consultants, ainsi que des leaders et des leaders afin de partager des id\u00e9es et d&rsquo;apprendre ensemble.<\/p>\n<p>L&rsquo;inscription \u00e0 n&rsquo;importe quel \u00e9v\u00e9nement de la s\u00e9rie vous inscrira automatiquement \u00e0 tous les \u00e9v\u00e9nements.<\/p>\n<h3>Jour des s\u00e9ances :<\/h3>\n<p>lundi<\/p>\n<h3>Horaires de toutes les s\u00e9ances :<\/h3>\n<p>Pr\u00e9sentation de 11h30 \u00e0 12h10. Discussion de 12h10 \u00e0 12h25<\/p>\n<h3>Dates des s\u00e9ances :<\/h3>\n<p>30 octobre, 13 novembre, 27 novembre, 11 d\u00e9cembre, 22 janvier, 5 f\u00e9vrier, 26 f\u00e9vrier, 18 mars, 25 mars, 29 avril, 13 mai, 3 juin, 10 juin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joignez-vous \u00e0 Jordan Sloan pour cette S\u00e9rie de ONLit, Le r\u00e9seau de coaching en litt\u00e9ratie. Notre travail commencera avec une \u00e9tude du livre de Jennifer Pierce et Kimberly St. Martin,&#8230;<\/p>\n","protected":false},"author":32,"featured_media":21105,"template":"","meta":{"_acf_changed":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"content-language":[507],"tribe_events_cat":[167],"class_list":["post-10000089","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","content-language-french","tribe_events_cat-book-study","cat_book-study","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"_links":{"self":[{"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tribe_events\/10000089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/users\/32"}],"version-history":[{"count":1,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tribe_events\/10000089\/revisions"}],"predecessor-version":[{"id":21482,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tribe_events\/10000089\/revisions\/21482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/media\/21105"}],"wp:attachment":[{"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/media?parent=10000089"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tags?post=10000089"},{"taxonomy":"content-language","embeddable":true,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/content-language?post=10000089"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/tgbl-onlit.tangiblelaunchpad.com\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=10000089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}